{"id":13352,"date":"2026-05-13T08:52:26","date_gmt":"2026-05-13T06:52:26","guid":{"rendered":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/?p=13352"},"modified":"2026-05-13T08:53:50","modified_gmt":"2026-05-13T06:53:50","slug":"u15-halbzeitpfiff-in-der-bol-aufstiegsrunde","status":"publish","type":"post","link":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/","title":{"rendered":"U15, Halbzeitpfiff in der BOL-Aufstiegsrunde"},"content":{"rendered":"\n<p style=\"font-weight: 400;\">Ambitioniert ging es im <strong>Saisonauftakt <\/strong>gegen SV Eintracht Penzendorf. Die Platzverh\u00e4ltnisse bei uns erforderten ein Ausw\u00e4rtsspiel. Nach einem fr\u00fchen und unn\u00f6tigen 2:0 R\u00fcckstand haben wir super reagiert und nahmen einen Punkt aus dem Saisonauftakt mit. Endstand: 2:2.<\/p>\n<p style=\"font-weight: 400;\">Am <strong>zweiten Spieltag <\/strong>waren wir G\u00e4ste beim 1. FC-VfL Pleinfeld. Zu diesem Zeitpunkt im Jahr ein super Spieluntergrund; ein Top Rasen. Nach Sichtung der Aufzeichnung unserer Veo Cam gab\u2019s zwei gef\u00e4hrliche Situation der Gastgeber, die Vanessa souver\u00e4n meisterte. Das dritte Tor haben wir erzwungen, allerdings ins eigene Tor. Endstand: 1:2 f\u00fcr uns.<\/p>\n<p style=\"font-weight: 400;\">Wegweisender <strong>dritter Spieltag<\/strong> beim 1. SC Feucht. Endstand: 3:0 verloren. Zus\u00e4tzlich nach wenigen Minuten einen Besuch mit Bruch in der Notaufnahme in Rummelsberg. Dieser 0er war schon fast eine Vorentscheidung.<\/p>\n<p style=\"font-weight: 400;\"><strong>Vierter Spieltag:<\/strong> Der Kopf war wieder frei, die G\u00e4ste aus Unterreichenbach besiegten wir mit 5:1. Diesmal im FRAPACK-Stadion in Gro\u00dfschwarzenlohe.<\/p>\n<p style=\"font-weight: 400;\">Durch Verschiebungen im Spielbetrieb wurde der <strong>f\u00fcnfte Spieltag<\/strong> wieder in Penzendorf angepfiffen. 1:0 bei tiefstehender Sonne gegen uns; den Kommentar zum Elfmeter gegen uns spare ich mir. Diesmal war ein anderer Spieler mit Bruch als Gast in der Notaufnahme. Endstand ohne weitere Verletzungen 2:0.<\/p>\n<p style=\"font-weight: 400;\"><strong>Spieltag #6:<\/strong> Heimspiel in Wendelstein. G\u00e4ste auf dem wieder bespielbarem Rasen war der 1. FC-VfL Pleinfeld. Die 1:0 F\u00fchrung aus der 5. Minute verwalteten wir bis zum Abpfiff. Drei Punkte f\u00fcr uns.<\/p>\n<p style=\"font-weight: 400;\">Zur Halbzeit der Saison m\u00fcssen nun der Fu\u00dfballgott, Zufall, Gl\u00fcck, \u2026 zu den Blues wechseln. Platz zwei ist weiterhin m\u00f6glich.<\/p>\n<p style=\"font-weight: 400;\">Halbzeitpfiff f\u00fcr: Vanessa, Alan, Ali, Dejan, Erhard, Fil, Jannik, Jannis, Jonas, Julian, Luis, Louis, Milian, Nico, Patrik, Philipp, Simon, Tim B., Tim H., Tu\u011fra &amp; Valentin.<\/p>\n<p style=\"font-weight: 400;\">Die Outtakes haben sich als Erfolg bewiesen und werden in Berichten schon fast von den Eltern eigefordert. Bittesch\u00f6n und ungefiltert:<\/p>\n<ul style=\"font-weight: 400;\">\n<li>Ey, Anfang April und ich brauch ein Thermo unterm Trikot!!!<\/li>\n<li>Wem geh\u00f6rt die Flasche?<\/li>\n<li>M\u00fcssen wir die Einnahmen vom Flaschenpfandsammeln eigentlich anmelden?<\/li>\n<li>Schon wieder einer im Krankenhaus mit Bruch.<\/li>\n<\/ul>\n<p>(Bericht: Stefan Fries)<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Ambitioniert ging es im Saisonauftakt gegen SV Eintracht Penzendorf. Die Platzverh\u00e4ltnisse bei uns erforderten ein Ausw\u00e4rtsspiel. Nach einem fr\u00fchen und unn\u00f6tigen 2:0 R\u00fcckstand haben wir super reagiert und nahmen einen Punkt aus dem Saisonauftakt mit. Endstand: 2:2. Am zweiten Spieltag waren wir G\u00e4ste beim 1. FC-VfL Pleinfeld. Zu diesem Zeitpunkt im Jahr ein super Spieluntergrund; [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":13353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"footnotes":""},"categories":[102],"tags":[],"class_list":["post-13352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-26-team-u15-3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>U15, Halbzeitpfiff in der BOL-Aufstiegsrunde - JFG Wendelstein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"U15, Halbzeitpfiff in der BOL-Aufstiegsrunde - JFG Wendelstein\" \/>\n<meta property=\"og:description\" content=\"Ambitioniert ging es im Saisonauftakt gegen SV Eintracht Penzendorf. Die Platzverh\u00e4ltnisse bei uns erforderten ein Ausw\u00e4rtsspiel. Nach einem fr\u00fchen und unn\u00f6tigen 2:0 R\u00fcckstand haben wir super reagiert und nahmen einen Punkt aus dem Saisonauftakt mit. Endstand: 2:2. Am zweiten Spieltag waren wir G\u00e4ste beim 1. FC-VfL Pleinfeld. Zu diesem Zeitpunkt im Jahr ein super Spieluntergrund; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/\" \/>\n<meta property=\"og:site_name\" content=\"JFG Wendelstein\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T06:52:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T06:53:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-content\/uploads\/2026\/05\/001_Halbzeit_BOL_Aufstiegsrunde-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dominik Jaworski\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dominikj\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dominik Jaworski\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\\\/\"},\"author\":{\"name\":\"Dominik Jaworski\",\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1fdca0e71be92900ef8521c9118d467d\"},\"headline\":\"U15, Halbzeitpfiff in der BOL-Aufstiegsrunde\",\"datePublished\":\"2026-05-13T06:52:26+00:00\",\"dateModified\":\"2026-05-13T06:53:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\\\/\"},\"wordCount\":330,\"image\":{\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/001_Halbzeit_BOL_Aufstiegsrunde-scaled.jpeg\",\"articleSection\":[\"26-team-u15-3\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\\\/\",\"url\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\\\/\",\"name\":\"U15, Halbzeitpfiff in der BOL-Aufstiegsrunde - JFG Wendelstein\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/001_Halbzeit_BOL_Aufstiegsrunde-scaled.jpeg\",\"datePublished\":\"2026-05-13T06:52:26+00:00\",\"dateModified\":\"2026-05-13T06:53:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1fdca0e71be92900ef8521c9118d467d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/001_Halbzeit_BOL_Aufstiegsrunde-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/001_Halbzeit_BOL_Aufstiegsrunde-scaled.jpeg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"U15, Halbzeitpfiff in der BOL-Aufstiegsrunde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/\",\"name\":\"JFG Wendelstein\",\"description\":\"Juniorenfu\u00dfball\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1fdca0e71be92900ef8521c9118d467d\",\"name\":\"Dominik Jaworski\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e05f57abbf9d0131cdd7ab704171b99ef68fe4dc45981b74ab44a89193e8c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e05f57abbf9d0131cdd7ab704171b99ef68fe4dc45981b74ab44a89193e8c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e05f57abbf9d0131cdd7ab704171b99ef68fe4dc45981b74ab44a89193e8c5?s=96&d=mm&r=g\",\"caption\":\"Dominik Jaworski\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/dominikj\"],\"url\":\"https:\\\/\\\/www.jugendfussball-wendelstein.de\\\/wordpress\\\/author\\\/dominikj\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"U15, Halbzeitpfiff in der BOL-Aufstiegsrunde - JFG Wendelstein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/","og_locale":"de_DE","og_type":"article","og_title":"U15, Halbzeitpfiff in der BOL-Aufstiegsrunde - JFG Wendelstein","og_description":"Ambitioniert ging es im Saisonauftakt gegen SV Eintracht Penzendorf. Die Platzverh\u00e4ltnisse bei uns erforderten ein Ausw\u00e4rtsspiel. Nach einem fr\u00fchen und unn\u00f6tigen 2:0 R\u00fcckstand haben wir super reagiert und nahmen einen Punkt aus dem Saisonauftakt mit. Endstand: 2:2. Am zweiten Spieltag waren wir G\u00e4ste beim 1. FC-VfL Pleinfeld. Zu diesem Zeitpunkt im Jahr ein super Spieluntergrund; [&hellip;]","og_url":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/","og_site_name":"JFG Wendelstein","article_published_time":"2026-05-13T06:52:26+00:00","article_modified_time":"2026-05-13T06:53:50+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-content\/uploads\/2026\/05\/001_Halbzeit_BOL_Aufstiegsrunde-scaled.jpeg","type":"image\/jpeg"}],"author":"Dominik Jaworski","twitter_card":"summary_large_image","twitter_creator":"@dominikj","twitter_misc":{"Verfasst von":"Dominik Jaworski","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/#article","isPartOf":{"@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/"},"author":{"name":"Dominik Jaworski","@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/#\/schema\/person\/1fdca0e71be92900ef8521c9118d467d"},"headline":"U15, Halbzeitpfiff in der BOL-Aufstiegsrunde","datePublished":"2026-05-13T06:52:26+00:00","dateModified":"2026-05-13T06:53:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/"},"wordCount":330,"image":{"@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-content\/uploads\/2026\/05\/001_Halbzeit_BOL_Aufstiegsrunde-scaled.jpeg","articleSection":["26-team-u15-3"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/","url":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/","name":"U15, Halbzeitpfiff in der BOL-Aufstiegsrunde - JFG Wendelstein","isPartOf":{"@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/#primaryimage"},"image":{"@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-content\/uploads\/2026\/05\/001_Halbzeit_BOL_Aufstiegsrunde-scaled.jpeg","datePublished":"2026-05-13T06:52:26+00:00","dateModified":"2026-05-13T06:53:50+00:00","author":{"@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/#\/schema\/person\/1fdca0e71be92900ef8521c9118d467d"},"breadcrumb":{"@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/#primaryimage","url":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-content\/uploads\/2026\/05\/001_Halbzeit_BOL_Aufstiegsrunde-scaled.jpeg","contentUrl":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-content\/uploads\/2026\/05\/001_Halbzeit_BOL_Aufstiegsrunde-scaled.jpeg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/u15-halbzeitpfiff-in-der-bol-aufstiegsrunde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"U15, Halbzeitpfiff in der BOL-Aufstiegsrunde"}]},{"@type":"WebSite","@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/#website","url":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/","name":"JFG Wendelstein","description":"Juniorenfu\u00dfball","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/#\/schema\/person\/1fdca0e71be92900ef8521c9118d467d","name":"Dominik Jaworski","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/32e05f57abbf9d0131cdd7ab704171b99ef68fe4dc45981b74ab44a89193e8c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e05f57abbf9d0131cdd7ab704171b99ef68fe4dc45981b74ab44a89193e8c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e05f57abbf9d0131cdd7ab704171b99ef68fe4dc45981b74ab44a89193e8c5?s=96&d=mm&r=g","caption":"Dominik Jaworski"},"sameAs":["https:\/\/x.com\/dominikj"],"url":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/author\/dominikj\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-json\/wp\/v2\/posts\/13352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-json\/wp\/v2\/comments?post=13352"}],"version-history":[{"count":2,"href":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-json\/wp\/v2\/posts\/13352\/revisions"}],"predecessor-version":[{"id":13356,"href":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-json\/wp\/v2\/posts\/13352\/revisions\/13356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-json\/wp\/v2\/media\/13353"}],"wp:attachment":[{"href":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-json\/wp\/v2\/media?parent=13352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-json\/wp\/v2\/categories?post=13352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jugendfussball-wendelstein.de\/wordpress\/wp-json\/wp\/v2\/tags?post=13352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}